

{"id":121,"date":"2023-07-17T06:29:28","date_gmt":"2023-07-17T06:29:28","guid":{"rendered":"https:\/\/srcentre.com.au\/?page_id=121"},"modified":"2024-02-16T13:16:04","modified_gmt":"2024-02-16T02:16:04","slug":"%e0%a8%96%e0%a9%8b%e0%a8%9c-%e0%a8%a8%e0%a8%b5%e0%a9%80%e0%a8%a8%e0%a8%a4%e0%a8%be","status":"publish","type":"page","link":"https:\/\/srcentre.com.au\/pa\/research-innovation\/","title":{"rendered":"\u0a16\u0a4b\u0a1c \u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"121\" class=\"elementor elementor-121\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ed55892 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2ed55892\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fd810b7\" data-id=\"6fd810b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-575b60d9 elementor-widget elementor-widget-shortcode\" data-id=\"575b60d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4504\" class=\"elementor elementor-4504\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccddb95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccddb95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86d2b40\" data-id=\"86d2b40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7653fec elementor-widget elementor-widget-spacer\" data-id=\"7653fec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4409a03f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4409a03f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70ac6741\" data-id=\"70ac6741\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1692661f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1692661f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-19e2b152\" data-id=\"19e2b152\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27f3e986 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"27f3e986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0a16\u0a4b\u0a1c \u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4530afaa\" data-id=\"4530afaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-34a9e6ab elementor-widget elementor-widget-spacer\" data-id=\"34a9e6ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-205203dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"205203dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27f0842c\" data-id=\"27f0842c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6087de77 elementor-widget elementor-widget-text-editor\" data-id=\"6087de77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a38\u0a3e\u0a21\u0a47 \u0a15\u0a4b\u0a32 \u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06 \u0a26\u0a40 \u0a06\u0a35\u0a3e\u0a1c\u0a3c \u0a28\u0a42\u0a70 \u0a39\u0a3e\u0a38\u0a32 \u0a15\u0a30\u0a28 \u0a32\u0a08 \u0a35\u0a3f\u0a27\u0a40 \u0a05\u0a24\u0a47 \u0a24\u0a15\u0a28\u0a3e\u0a32\u0a4b\u0a1c\u0a40 \u0a26\u0a4b\u0a35\u0a47\u0a02 \u0a39\u0a28\u0964 \u0a38\u0a3e\u0a21\u0a47 \u0a15\u0a4b\u0a32 \u0a2e\u0a3e\u0a24\u0a30\u0a3e\u0a24\u0a2e\u0a15 \u0a05\u0a24\u0a47 \u0a17\u0a41\u0a23\u0a3e\u0a24\u0a2e\u0a15 \u0a35\u0a3f\u0a27\u0a40\u0a06\u0a02 \u0a26\u0a40 \u0a07\u0a71\u0a15 \u0a35\u0a3f\u0a38\u0a3c\u0a3e\u0a32 \u0a38\u0a3c\u0a4d\u0a30\u0a47\u0a23\u0a40 \u0a35\u0a3f\u0a71\u0a1a \u0a05\u0a70\u0a26\u0a30\u0a42\u0a28\u0a40 \u0a2e\u0a41\u0a39\u0a3e\u0a30\u0a24 \u0a39\u0a48, \u0a1c\u0a3f\u0a38\u0a28\u0a42\u0a70 \u0a16\u0a4b\u0a1c\u0a15\u0a30\u0a24\u0a3e\u0a35\u0a3e\u0a02, \u0a2e\u0a41\u0a32\u0a3e\u0a02\u0a15\u0a23\u0a15\u0a3e\u0a30\u0a3e\u0a02, \u0a05\u0a70\u0a15\u0a5c\u0a3e \u0a35\u0a3f\u0a17\u0a3f\u0a06\u0a28\u0a40\u0a06\u0a02, \u0a2a\u0a4d\u0a30\u0a4b\u0a17\u0a30\u0a3e\u0a2e\u0a30\u0a3e\u0a02 \u0a05\u0a24\u0a47 \u0a24\u0a15\u0a28\u0a40\u0a15\u0a40 \u0a2e\u0a3e\u0a39\u0a3f\u0a30\u0a3e\u0a02 \u0a26\u0a40 \u0a07\u0a71\u0a15 \u0a09\u0a71\u0a1a \u0a39\u0a41\u0a28\u0a30\u0a2e\u0a70\u0a26 \u0a1f\u0a40\u0a2e \u0a26\u0a41\u0a06\u0a30\u0a3e \u0a38\u0a2e\u0a30\u0a25\u0a24 \u0a15\u0a40\u0a24\u0a3e \u0a1c\u0a3e\u0a02\u0a26\u0a3e \u0a39\u0a48\u0964<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-89983f3\" data-id=\"89983f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7baf4c89 elementor-widget elementor-widget-spacer\" data-id=\"7baf4c89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d564e8e elementor-widget elementor-widget-shortcode\" data-id=\"d564e8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4493\" class=\"elementor elementor-4493\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48d9fba4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48d9fba4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-595dc736\" data-id=\"595dc736\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55c436d1 elementor-widget elementor-widget-heading\" data-id=\"55c436d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06 \u0a35\u0a3f\u0a71\u0a1a \u0a1c\u0a3c\u0a3f\u0a70\u0a26\u0a17\u0a40\u2122<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6a7e7b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7c6a7e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-wts-url=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/12\/SRC_LinA-client-brochure_for-email.pdf\" data-wts-link=\"yes\" data-wts-new-window=\"yes\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-8961ce1 ae-link-yes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8961ce1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7fcfc9a\" data-id=\"7fcfc9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2aeed2 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"e2aeed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2040\" height=\"1148\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2024\/02\/SRC_LinA_Main-Image.png\" class=\"attachment-full size-full wp-image-13069\" alt=\"\u0a38\u0a5c\u0a15 \u0a2a\u0a3e\u0a30 \u0a15\u0a30\u0a26\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a40 \u0a2d\u0a40\u0a5c, \u0a09\u0a71\u0a2a\u0a30 \u0a28\u0a40\u0a32\u0a47 \u0a17\u0a4d\u0a30\u0a3e\u0a2b\u0a3f\u0a15\u0a38 \u0a28\u0a3e\u0a32, \u0a35\u0a71\u0a16-\u0a35\u0a71\u0a16 \u0a06\u0a35\u0a3e\u0a1c\u0a3c\u0a3e\u0a02 \u0a28\u0a42\u0a70 \u0a26\u0a30\u0a38\u0a3e\u0a09\u0a02\u0a26\u0a40 \u0a39\u0a48\u0964\" srcset=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2024\/02\/SRC_LinA_Main-Image.png 2040w, https:\/\/srcentre.com.au\/wp-content\/uploads\/2024\/02\/SRC_LinA_Main-Image-300x169.png 300w, https:\/\/srcentre.com.au\/wp-content\/uploads\/2024\/02\/SRC_LinA_Main-Image-1024x576.png 1024w, https:\/\/srcentre.com.au\/wp-content\/uploads\/2024\/02\/SRC_LinA_Main-Image-768x432.png 768w, https:\/\/srcentre.com.au\/wp-content\/uploads\/2024\/02\/SRC_LinA_Main-Image-1536x864.png 1536w, https:\/\/srcentre.com.au\/wp-content\/uploads\/2024\/02\/SRC_LinA_Main-Image-18x10.png 18w\" sizes=\"(max-width: 2040px) 100vw, 2040px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fe288d0\" data-id=\"fe288d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fafb383 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fafb383\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29a334e\" data-id=\"29a334e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf38148 elementor-widget elementor-widget-text-editor\" data-id=\"cf38148\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06 \u0a35\u0a3f\u0a71\u0a1a \u0a1c\u0a40\u0a35\u0a28\u2122 \u0a38\u0a3e\u0a21\u0a40 \u0a16\u0a4b\u0a1c \u0a35\u0a3f\u0a27\u0a40 \u0a26\u0a47 \u0a15\u0a47\u0a02\u0a26\u0a30 \u0a35\u0a3f\u0a71\u0a1a \u0a39\u0a48\u0964 \u0a26\u0a47\u0a38\u0a3c \u0a26\u0a47 \u0a38\u0a2d \u0a24\u0a4b\u0a02 \u0a35\u0a71\u0a27 \u0a35\u0a3f\u0a27\u0a40\u0a17\u0a24 \u0a24\u0a4c\u0a30 &#039;\u0a24\u0a47 \u0a38\u0a16\u0a3c\u0a24 \u0a05\u0a24\u0a47 \u0a2a\u0a4d\u0a30\u0a24\u0a40\u0a28\u0a3f\u0a27\u0a40 \u0a14\u0a28\u0a32\u0a3e\u0a08\u0a28 \u0a2a\u0a48\u0a28\u0a32 \u0a26\u0a47 \u0a30\u0a42\u0a2a \u0a35\u0a3f\u0a71\u0a1a, \u0a1c\u0a40\u0a35\u0a28 \u0a35\u0a3f\u0a71\u0a1a \u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06\u2122, \u0a26\u0a47\u0a38\u0a3c \u0a26\u0a40 \u0a06\u0a35\u0a3e\u0a1c\u0a3c \u0a05\u0a24\u0a47 \u0a35\u0a3f\u0a1a\u0a3e\u0a30\u0a3e\u0a02 \u0a28\u0a42\u0a70 \u0a26\u0a30\u0a38\u0a3e\u0a09\u0a02\u0a26\u0a3e \u0a39\u0a48\u0964<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e521066\" data-id=\"e521066\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a116279 elementor-widget elementor-widget-spacer\" data-id=\"a116279\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-wts-url=\"\/lifeinaustralia\/\" data-wts-link=\"yes\" data-wts-new-window=\"\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-bee9618 ae-link-yes src_button_link elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bee9618\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-07d66cc\" data-id=\"07d66cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ff3076 elementor-widget__width-auto item_text elementor-widget elementor-widget-text-editor\" data-id=\"0ff3076\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a39\u0a4b\u0a30 \u0a1c\u0a3e\u0a23\u0a4b<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e14e71d elementor-widget__width-auto item_icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e14e71d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"42\" height=\"35\" viewbox=\"0 0 42 35\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M41.4942 17.1141L41.4938 17.1136L41.4942 17.1131L40.447 16.0659L40.4466 16.0664L24.3802 0L23.333 1.0472L38.5766 16.2908H0V17.7718H38.7412L23.333 33.18L24.3802 34.2272L40.4466 18.1608L40.447 18.1613L41.4942 17.1141Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab236b4 elementor-widget elementor-widget-spacer\" data-id=\"ab236b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95fb33d elementor-widget elementor-widget-shortcode\" data-id=\"95fb33d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4498\" class=\"elementor elementor-4498\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14b44721 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14b44721\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26570343\" data-id=\"26570343\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f1cb08b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f1cb08b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2c68f05a\" data-id=\"2c68f05a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ba5277 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"19ba5277\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06\u0a08 \u0a38\u0a2e\u0a3e\u0a1c \u0a2c\u0a3e\u0a30\u0a47 \u0a38\u0a3e\u0a21\u0a40 \u0a38\u0a2e\u0a1d \u0a28\u0a42\u0a70 \u0a05\u0a71\u0a17\u0a47 \u0a35\u0a27\u0a3e\u0a09\u0a23 \u0a05\u0a24\u0a47 \u0a38\u0a3e\u0a30\u0a3f\u0a06\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a07\u0a26\u0a47 \u0a32\u0a08 \u0a38\u0a2c\u0a42\u0a24-\u0a05\u0a27\u0a3e\u0a30\u0a24 \u0a28\u0a40\u0a24\u0a40 \u0a35\u0a3f\u0a15\u0a3e\u0a38 \u0a26\u0a3e \u0a38\u0a2e\u0a30\u0a25\u0a28 \u0a15\u0a30\u0a28 \u0a32\u0a08 \u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e\u0a15\u0a3e\u0a30\u0a40 \u0a38\u0a2e\u0a3e\u0a1c\u0a3f\u0a15 \u0a16\u0a4b\u0a1c \u0a26\u0a40 \u0a05\u0a17\u0a35\u0a3e\u0a08 \u0a15\u0a30\u0a28\u0a3e\u0964<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-020efbd elementor-widget elementor-widget-shortcode\" data-id=\"020efbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4500\" class=\"elementor elementor-4500\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f6f15cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f6f15cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ceb8f06\" data-id=\"4ceb8f06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55edd6ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55edd6ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7b64fad5\" data-id=\"7b64fad5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21ebfe1 elementor-widget elementor-widget-spacer\" data-id=\"21ebfe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c498ac0 elementor-widget elementor-widget-heading\" data-id=\"1c498ac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0a16\u0a4b\u0a1c \u0a26\u0a47 \u0a22\u0a70\u0a17<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d90241b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2d90241b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-646b917 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"646b917\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-feb3f94\" data-id=\"feb3f94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe23243 elementor-widget elementor-widget-image\" data-id=\"fe23243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_innovation_methods_research.svg\" class=\"attachment-full size-full wp-image-5018\" alt=\"\u0a38\u0a42\u0a16\u0a2e \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30 \u0a26\u0a40\u0a06\u0a02 \u0a15\u0a24\u0a3e\u0a30\u0a3e\u0a02 \u0a1c\u0a3f\u0a28\u0a4d\u0a39\u0a3e\u0a02 \u0a35\u0a3f\u0a71\u0a1a \u0a15\u0a41\u0a1d \u0a17\u0a3e\u0a07\u0a2c \u0a39\u0a28\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-04dfdec elementor-widget elementor-widget-spacer\" data-id=\"04dfdec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-524ebef9 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"524ebef9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-757268c\" data-id=\"757268c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-396f165f elementor-widget elementor-widget-text-editor\" data-id=\"396f165f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a07\u0a70\u0a1f\u0a30\u0a10\u0a15\u0a1f\u0a3f\u0a35 \u0a21\u0a47\u0a1f\u0a3e \u0a15\u0a39\u0a3e\u0a23\u0a40 \u0a38\u0a41\u0a23\u0a3e\u0a09\u0a23\u0a3e<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-377e951 elementor-widget elementor-widget-text-editor\" data-id=\"377e951\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a24\u0a41\u0a38\u0a40\u0a02 \u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06 \u0a26\u0a40 \u0a2a\u0a42\u0a30\u0a40 \u0a06\u0a2c\u0a3e\u0a26\u0a40 \u0a28\u0a42\u0a70 \u0a26\u0a30\u0a38\u0a3e\u0a09\u0a23 \u0a32\u0a08 3000 \u0a38\u0a30\u0a35\u0a47\u0a16\u0a23 \u0a1c\u0a35\u0a3e\u0a2c\u0a3e\u0a02 \u0a26\u0a40 \u0a35\u0a30\u0a24\u0a4b\u0a02 \u0a15\u0a3f\u0a35\u0a47\u0a02 \u0a15\u0a30\u0a26\u0a47 \u0a39\u0a4b?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-498acf19\" data-id=\"498acf19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f04f19b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f04f19b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-abe0b0a\" data-id=\"abe0b0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6ad327 elementor-widget elementor-widget-image\" data-id=\"e6ad327\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/methods_research_image_1.svg\" class=\"attachment-full size-full wp-image-5026\" alt=\"\u0a35\u0a71\u0a16-\u0a35\u0a71\u0a16 \u0a06\u0a15\u0a3e\u0a30\u0a3e\u0a02 \u0a35\u0a3f\u0a71\u0a1a \u0a38\u0a71\u0a24 \u0a21\u0a3f\u0a71\u0a17\u0a26\u0a47 \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c5cb477 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5cb477\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a726431\" data-id=\"a726431\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6401c6a elementor-widget elementor-widget-text-editor\" data-id=\"6401c6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/12\/ACSSM-Analytical-Report-20231005.pdf\" target=\"_blank\" rel=\"noopener\">\u0a38\u0a30\u0a35\u0a47\u0a16\u0a23 \u0a35\u0a3f\u0a27\u0a40\u0a06\u0a02 \u0a26\u0a3e \u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06\u0a08 \u0a24\u0a41\u0a32\u0a28\u0a3e\u0a24\u0a2e\u0a15 \u0a05\u0a27\u0a3f\u0a10\u0a28<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58e250c elementor-widget elementor-widget-text-editor\" data-id=\"58e250c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">\u0a38\u0a25\u0a3e\u0a2a\u0a3f\u0a24 \u0a05\u0a24\u0a47 \u0a09\u0a71\u0a2d\u0a30 \u0a30\u0a39\u0a47 \u0a38\u0a30\u0a35\u0a47\u0a16\u0a23 \u0a24\u0a30\u0a40\u0a15\u0a3f\u0a06\u0a02 \u0a26\u0a40 \u0a38\u0a2e\u0a15\u0a3e\u0a32\u0a40 \u0a38\u0a3c\u0a41\u0a71\u0a27\u0a24\u0a3e \u0a28\u0a42\u0a70 \u0a38\u0a2e\u0a1d\u0a4b \u0a05\u0a24\u0a47 \u0a07\u0a39 \u0a28\u0a3f\u0a30\u0a27\u0a3e\u0a30\u0a24 \u0a15\u0a30\u0a4b \u0a15\u0a3f \u0a15\u0a40 \u0a38\u0a2e\u0a47\u0a02 \u0a26\u0a47 \u0a28\u0a3e\u0a32 \u0a38\u0a70\u0a2d\u0a3e\u0a35\u0a28\u0a3e-\u0a05\u0a27\u0a3e\u0a30\u0a24 \u0a2a\u0a39\u0a41\u0a70\u0a1a\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a07\u0a26\u0a47 \u0a35\u0a3f\u0a71\u0a1a \u0a15\u0a2e\u0a40 \u0a06\u0a08 \u0a39\u0a48\u0964<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559685&quot;:20,&quot;335559738&quot;:40,&quot;335559739&quot;:40,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-43eb63d\" data-id=\"43eb63d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bfa42b4\" data-id=\"bfa42b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dea9d1 elementor-widget elementor-widget-image\" data-id=\"6dea9d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/methods_research_image_2.png\" class=\"attachment-full size-full wp-image-5027\" alt=\"\u0a35\u0a3e\u0a08\u0a1f\u0a2c\u0a4b\u0a30\u0a21 &#039;\u0a24\u0a47 \u0a32\u0a3f\u0a16 \u0a30\u0a39\u0a47 \u0a35\u0a3f\u0a05\u0a15\u0a24\u0a40 \u0a26\u0a40 \u0a28\u0a40\u0a32\u0a40 \u0a21\u0a42\u0a13\u0a1f\u0a4b\u0a28 \u0a24\u0a38\u0a35\u0a40\u0a30\u0964\" srcset=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/methods_research_image_2.png 640w, https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/methods_research_image_2-300x200.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bbd8b6b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbd8b6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a8bc1c6\" data-id=\"a8bc1c6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08f7d43 elementor-widget elementor-widget-text-editor\" data-id=\"08f7d43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/polis.cass.anu.edu.au\/files\/docs\/2025\/6\/The_Effects_of_Mode_on_Answers.pdf\" target=\"_blank\" rel=\"noopener\">\u0a38\u0a70\u0a2d\u0a3e\u0a35\u0a28\u0a3e-\u0a05\u0a27\u0a3e\u0a30\u0a24 \u0a2e\u0a3f\u0a38\u0a3c\u0a30\u0a24-\u0a2e\u0a4b\u0a21 \u0a14\u0a28\u0a32\u0a3e\u0a08\u0a28 \u0a2a\u0a48\u0a28\u0a32 \u0a16\u0a4b\u0a1c \u0a35\u0a3f\u0a71\u0a1a \u0a09\u0a71\u0a24\u0a30\u0a3e\u0a02 &#039;\u0a24\u0a47 \u0a2e\u0a4b\u0a21 \u0a26\u0a47 \u0a2a\u0a4d\u0a30\u0a2d\u0a3e\u0a35<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9088ba6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9088ba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a05\u0a30\u0a27-\u0a2a\u0a4d\u0a30\u0a2f\u0a4b\u0a17\u0a3e\u0a24\u0a2e\u0a15 \u0a21\u0a3f\u0a1c\u0a3c\u0a3e\u0a08\u0a28 \u0a35\u0a3f\u0a71\u0a1a \u0a38\u0a35\u0a48-\u0a1a\u0a4b\u0a23 \u0a2a\u0a4d\u0a30\u0a2d\u0a3e\u0a35 \u0a28\u0a42\u0a70 \u0a28\u0a3f\u0a2f\u0a70\u0a24\u0a30\u0a3f\u0a24 \u0a15\u0a30\u0a28 \u0a32\u0a08 \u0a38\u0a2c\u0a42\u0a24 \u0a05\u0a24\u0a47 \u0a2e\u0a47\u0a32 \u0a16\u0a3e\u0a02\u0a26\u0a47 \u0a24\u0a30\u0a40\u0a15\u0a47<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e7e049\" data-id=\"2e7e049\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cdb0a8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdb0a8c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-160c178\" data-id=\"160c178\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6898536 elementor-widget elementor-widget-image\" data-id=\"6898536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/methods_research_image_1.svg\" class=\"attachment-full size-full wp-image-5026\" alt=\"\u0a35\u0a71\u0a16-\u0a35\u0a71\u0a16 \u0a06\u0a15\u0a3e\u0a30\u0a3e\u0a02 \u0a35\u0a3f\u0a71\u0a1a \u0a38\u0a71\u0a24 \u0a21\u0a3f\u0a71\u0a17\u0a26\u0a47 \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dea6274 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dea6274\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-162cb54\" data-id=\"162cb54\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f790b67 elementor-widget elementor-widget-text-editor\" data-id=\"f790b67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2024\/08\/Socio-demographic-Characteristics-of-Telephone-Access-in-Australia-Implications-for-Survey-Research.pdf\">\u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06 \u0a35\u0a3f\u0a71\u0a1a \u0a1f\u0a48\u0a32\u0a40\u0a2b\u0a4b\u0a28 \u0a2a\u0a39\u0a41\u0a70\u0a1a \u0a26\u0a40\u0a06\u0a02 \u0a38\u0a2e\u0a3e\u0a1c\u0a3f\u0a15-\u0a1c\u0a28\u0a38\u0a70\u0a16\u0a3f\u0a06 \u0a35\u0a3f\u0a38\u0a3c\u0a47\u0a38\u0a3c\u0a24\u0a3e\u0a35\u0a3e\u0a02 - \u0a38\u0a30\u0a35\u0a47\u0a16\u0a23 \u0a16\u0a4b\u0a1c \u0a32\u0a08 \u0a2a\u0a4d\u0a30\u0a2d\u0a3e\u0a35<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a3f5897\" data-id=\"a3f5897\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31eafff\" data-id=\"31eafff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6e1fe7 elementor-widget elementor-widget-image\" data-id=\"e6e1fe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/methods_research_image_1.svg\" class=\"attachment-full size-full wp-image-5026\" alt=\"\u0a35\u0a71\u0a16-\u0a35\u0a71\u0a16 \u0a06\u0a15\u0a3e\u0a30\u0a3e\u0a02 \u0a35\u0a3f\u0a71\u0a1a \u0a38\u0a71\u0a24 \u0a21\u0a3f\u0a71\u0a17\u0a26\u0a47 \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-df5aa14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df5aa14\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59f9dab\" data-id=\"59f9dab\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c84226 elementor-widget elementor-widget-text-editor\" data-id=\"2c84226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/academic.oup.com\/jssam\/advance-article-abstract\/doi\/10.1093\/jssam\/smaf019\/8443212?utm_source=authortollfreelink&amp;utm_campaign=jssam&amp;utm_medium=email\" target=\"_blank\" rel=\"noopener\">Reducing the Bias From Probability and Nonprobability Online Panels by Excluding Satisficers<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e4ebc12\" data-id=\"e4ebc12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8064e01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8064e01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c59f65e\" data-id=\"c59f65e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a0ae6d elementor-widget elementor-widget-spacer\" data-id=\"9a0ae6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8692bdd elementor-widget elementor-widget-shortcode\" data-id=\"8692bdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4502\" class=\"elementor elementor-4502\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6911d134 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6911d134\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f801bfd\" data-id=\"f801bfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e8660ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e8660ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-23c7ed01\" data-id=\"23c7ed01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f8acbf7 elementor-widget elementor-widget-heading\" data-id=\"1f8acbf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0a16\u0a4b\u0a1c \u0a38\u0a47\u0a35\u0a3e\u0a35\u0a3e\u0a02<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c5fd431 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2c5fd431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e182bd6 elementor-widget elementor-widget-spacer\" data-id=\"e182bd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2db3440a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2db3440a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7c7490eb\" data-id=\"7c7490eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-488cd1d elementor-widget elementor-widget-text-editor\" data-id=\"488cd1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a38\u0a3e\u0a21\u0a47 \u0a15\u0a4b\u0a32 \u0a2e\u0a3e\u0a24\u0a30\u0a3e\u0a24\u0a2e\u0a15 \u0a05\u0a24\u0a47 \u0a17\u0a41\u0a23\u0a3e\u0a24\u0a2e\u0a15 \u0a35\u0a3f\u0a27\u0a40\u0a06\u0a02 \u0a26\u0a40 \u0a07\u0a71\u0a15 \u0a35\u0a3f\u0a38\u0a3c\u0a3e\u0a32 \u0a38\u0a3c\u0a4d\u0a30\u0a47\u0a23\u0a40 \u0a35\u0a3f\u0a71\u0a1a \u0a05\u0a70\u0a26\u0a30\u0a42\u0a28\u0a40 \u0a2e\u0a41\u0a39\u0a3e\u0a30\u0a24 \u0a39\u0a48, \u0a1c\u0a3f\u0a38\u0a28\u0a42\u0a70 \u0a16\u0a4b\u0a1c\u0a15\u0a30\u0a24\u0a3e\u0a35\u0a3e\u0a02, \u0a2e\u0a41\u0a32\u0a3e\u0a02\u0a15\u0a23\u0a15\u0a3e\u0a30\u0a3e\u0a02, \u0a05\u0a70\u0a15\u0a5c\u0a3e \u0a35\u0a3f\u0a17\u0a3f\u0a06\u0a28\u0a40\u0a06\u0a02, \u0a2a\u0a4d\u0a30\u0a4b\u0a17\u0a30\u0a3e\u0a2e\u0a30\u0a3e\u0a02 \u0a05\u0a24\u0a47 \u0a24\u0a15\u0a28\u0a40\u0a15\u0a40 \u0a2e\u0a3e\u0a39\u0a3f\u0a30\u0a3e\u0a02 \u0a26\u0a40 \u0a07\u0a71\u0a15 \u0a09\u0a71\u0a1a \u0a39\u0a41\u0a28\u0a30\u0a2e\u0a70\u0a26 \u0a1f\u0a40\u0a2e \u0a26\u0a41\u0a06\u0a30\u0a3e \u0a38\u0a2e\u0a30\u0a25\u0a24 \u0a15\u0a40\u0a24\u0a3e \u0a1c\u0a3e\u0a02\u0a26\u0a3e \u0a39\u0a48\u0964<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5df91e8e\" data-id=\"5df91e8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-wts-url=\"\/research-services\/\" data-wts-link=\"yes\" data-wts-new-window=\"\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c00169 ae-link-yes src_button_link elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c00169\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ddf9810\" data-id=\"ddf9810\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a93935 elementor-widget__width-auto item_text elementor-widget elementor-widget-text-editor\" data-id=\"6a93935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0a38\u0a3e\u0a21\u0a40\u0a06\u0a02 \u0a16\u0a4b\u0a1c \u0a38\u0a47\u0a35\u0a3e\u0a35\u0a3e\u0a02<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aec2f43 elementor-widget__width-auto item_icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"aec2f43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"42\" height=\"35\" viewbox=\"0 0 42 35\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M41.4942 17.1141L41.4938 17.1136L41.4942 17.1131L40.447 16.0659L40.4466 16.0664L24.3802 0L23.333 1.0472L38.5766 16.2908H0V17.7718H38.7412L23.333 33.18L24.3802 34.2272L40.4466 18.1608L40.447 18.1613L41.4942 17.1141Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4acfd9b elementor-widget elementor-widget-spacer\" data-id=\"4acfd9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c931d4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c931d4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e53b76e\" data-id=\"e53b76e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-96b13cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96b13cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bbc3f9e\" data-id=\"bbc3f9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eabe8a elementor-widget elementor-widget-image\" data-id=\"3eabe8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_services.01.questionaire_design_and_testing.svg\" class=\"attachment-full size-full wp-image-5044\" alt=\"\u0a35\u0a71\u0a16-\u0a35\u0a71\u0a16 \u0a06\u0a15\u0a3e\u0a30 \u0a26\u0a47 \u0a28\u0a40\u0a32\u0a47 \u0a2c\u0a3f\u0a70\u0a26\u0a40\u0a06\u0a02 \u0a26\u0a40\u0a06\u0a02 \u0a2a\u0a70\u0a1c \u0a15\u0a24\u0a3e\u0a30\u0a3e\u0a02\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cc717d elementor-widget elementor-widget-text-editor\" data-id=\"1cc717d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0a2a\u0a4d\u0a30\u0a38\u0a3c\u0a28\u0a3e\u0a35\u0a32\u0a40 \u0a21\u0a3f\u0a1c\u0a3c\u0a3e\u0a08\u0a28 \u0a05\u0a24\u0a47 \u0a1f\u0a48\u0a38\u0a1f\u0a3f\u0a70\u0a17<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e53f19a\" data-id=\"e53f19a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-26e0f68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26e0f68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-23dcf5c\" data-id=\"23dcf5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4825d89 elementor-widget elementor-widget-image\" data-id=\"4825d89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_services.02.survey_research.svg\" class=\"attachment-full size-full wp-image-5045\" alt=\"\u0a1a\u0a3e\u0a30 \u0a35\u0a71\u0a16-\u0a35\u0a71\u0a16 \u0a06\u0a15\u0a3e\u0a30 \u0a26\u0a47, \u0a32\u0a1f\u0a15\u0a26\u0a47 \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09aa6cc elementor-widget elementor-widget-text-editor\" data-id=\"09aa6cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0a38\u0a30\u0a35\u0a47\u0a16\u0a23 \u0a16\u0a4b\u0a1c<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-df70736\" data-id=\"df70736\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-84c5be0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84c5be0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c2c2913\" data-id=\"c2c2913\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5bef76 elementor-widget elementor-widget-image\" data-id=\"f5bef76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_services.03.cognitive_interviewing.svg\" class=\"attachment-full size-full wp-image-5046\" alt=\"\u0a17\u0a4b\u0a32 \u0a2a\u0a3e\u0a38\u0a3f\u0a06\u0a02 \u0a28\u0a42\u0a70 \u0a1b\u0a42\u0a39\u0a23 \u0a35\u0a3e\u0a32\u0a47 \u0a26\u0a4b \u0a35\u0a71\u0a21\u0a47 \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-133b5c4 elementor-widget elementor-widget-text-editor\" data-id=\"133b5c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0a2c\u0a4b\u0a27\u0a3e\u0a24\u0a2e\u0a15 \u0a07\u0a70\u0a1f\u0a30\u0a35\u0a3f\u0a0a<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e8c2fba\" data-id=\"e8c2fba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ee780df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee780df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-afa1135\" data-id=\"afa1135\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc700df elementor-widget elementor-widget-image\" data-id=\"bc700df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_services.04.qualitative_research.svg\" class=\"attachment-full size-full wp-image-5047\" alt=\"\u0a05\u0a71\u0a20\u0a3e\u0a02 \u0a26\u0a40 \u0a07\u0a71\u0a15 \u0a1b\u0a71\u0a32\u0a40, \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5992589 elementor-widget elementor-widget-text-editor\" data-id=\"5992589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0a17\u0a41\u0a23\u0a3e\u0a24\u0a2e\u0a15 \u0a16\u0a4b\u0a1c<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-068a3f9 elementor-widget elementor-widget-spacer\" data-id=\"068a3f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1df78f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1df78f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-da1d12d\" data-id=\"da1d12d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b333ece elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b333ece\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-32565ab\" data-id=\"32565ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-544147a elementor-widget elementor-widget-image\" data-id=\"544147a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_services.05.data_analytics.svg\" class=\"attachment-full size-full wp-image-5048\" alt=\"\u0a35\u0a71\u0a16-\u0a35\u0a71\u0a16 \u0a06\u0a15\u0a3e\u0a30 \u0a26\u0a47 \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30 \u0a26\u0a40\u0a06\u0a02 \u0a1b\u0a47 \u0a15\u0a24\u0a3e\u0a30\u0a3e\u0a02\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e214a70 elementor-widget elementor-widget-text-editor\" data-id=\"e214a70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0a21\u0a3e\u0a1f\u0a3e \u0a35\u0a3f\u0a38\u0a3c\u0a32\u0a47\u0a38\u0a3c\u0a23<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3ca0fb1\" data-id=\"3ca0fb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-07e7b7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07e7b7b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4ebc22e\" data-id=\"4ebc22e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fafdfb6 elementor-widget elementor-widget-image\" data-id=\"fafdfb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_services.06.data_visualisation_and_reporting.svg\" class=\"attachment-full size-full wp-image-5049\" alt=\"\u0a2c\u0a3e\u0a30\u0a3e\u0a02 \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30 \u0a26\u0a3e \u0a07\u0a71\u0a15 \u0a16\u0a3f\u0a70\u0a21\u0a3f\u0a06 \u0a39\u0a4b\u0a07\u0a06 \u0a38\u0a2e\u0a42\u0a39\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-248fe12 elementor-widget elementor-widget-text-editor\" data-id=\"248fe12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0a21\u0a3e\u0a1f\u0a3e \u0a35\u0a3f\u0a1c\u0a3c\u0a42\u0a05\u0a32\u0a3e\u0a08\u0a1c\u0a3c\u0a47\u0a38\u0a3c\u0a28 \u0a05\u0a24\u0a47 \u0a30\u0a3f\u0a2a\u0a4b\u0a30\u0a1f\u0a3f\u0a70\u0a17<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b7b43cd\" data-id=\"b7b43cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b2f9284 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2f9284\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1985403\" data-id=\"1985403\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15938f7 elementor-widget elementor-widget-image\" data-id=\"15938f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_services.07.evaluation.svg\" class=\"attachment-full size-full wp-image-5050\" alt=\"\u0a05\u0a71\u0a20 \u0a20\u0a4b\u0a38 \u0a28\u0a40\u0a32\u0a47 \u0a05\u0a70\u0a21\u0a3e\u0a15\u0a3e\u0a30\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59118ea elementor-widget elementor-widget-text-editor\" data-id=\"59118ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0a2e\u0a41\u0a32\u0a3e\u0a02\u0a15\u0a23<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d952c32\" data-id=\"d952c32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-13d3532 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13d3532\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4069f71\" data-id=\"4069f71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eb7901 elementor-widget elementor-widget-image\" data-id=\"5eb7901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/08\/research_services.08.data_management.svg\" class=\"attachment-full size-full wp-image-5051\" alt=\"\u0a35\u0a71\u0a16-\u0a35\u0a71\u0a16 \u0a06\u0a15\u0a3e\u0a30\u0a3e\u0a02 \u0a26\u0a47 \u0a28\u0a40\u0a32\u0a47 \u0a1a\u0a71\u0a15\u0a30\u0a3e\u0a02 \u0a26\u0a3e \u0a07\u0a71\u0a15 \u0a17\u0a30\u0a3f\u0a71\u0a21\u0964\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12de981 elementor-widget elementor-widget-text-editor\" data-id=\"12de981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u0a21\u0a3e\u0a1f\u0a3e \u0a2a\u0a4d\u0a30\u0a2c\u0a70\u0a27\u0a28<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6568e75 elementor-widget elementor-widget-spacer\" data-id=\"6568e75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-121","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Research innovation - Social Research Centre<\/title>\n<meta name=\"description\" content=\"We have both the methodology and technology to capture the voice of Australia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/srcentre.com.au\/pa\/\u0a16\u0a4b\u0a1c-\u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e\/\" \/>\n<meta property=\"og:locale\" content=\"pa_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Research innovation\" \/>\n<meta property=\"og:description\" content=\"We have both the methodology and technology to capture the voice of Australia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/srcentre.com.au\/pa\/\u0a16\u0a4b\u0a1c-\u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e\/\" \/>\n<meta property=\"og:site_name\" content=\"Social Research Centre\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SRCentreAUS\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T02:16:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SRCentreAUS\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/research-innovation\\\/\",\"url\":\"https:\\\/\\\/srcentre.com.au\\\/research-innovation\\\/\",\"name\":\"Research innovation - Social Research Centre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/#website\"},\"datePublished\":\"2023-07-17T06:29:28+00:00\",\"dateModified\":\"2024-02-16T02:16:04+00:00\",\"description\":\"We have both the methodology and technology to capture the voice of Australia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/research-innovation\\\/#breadcrumb\"},\"inLanguage\":\"pa-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/srcentre.com.au\\\/research-innovation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/research-innovation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/srcentre.com.au\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Research innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/#website\",\"url\":\"https:\\\/\\\/srcentre.com.au\\\/\",\"name\":\"Social Research Centre\",\"description\":\"Social Research Centre\",\"publisher\":{\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/srcentre.com.au\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pa-IN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/#organization\",\"name\":\"Social Research Centre\",\"url\":\"https:\\\/\\\/srcentre.com.au\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pa-IN\",\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/srcentre.com.au\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/src-icon.svg\",\"contentUrl\":\"https:\\\/\\\/srcentre.com.au\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/src-icon.svg\",\"width\":135,\"height\":135,\"caption\":\"Social Research Centre\"},\"image\":{\"@id\":\"https:\\\/\\\/srcentre.com.au\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SRCentreAUS\\\/\",\"https:\\\/\\\/x.com\\\/SRCentreAUS\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0a16\u0a4b\u0a1c \u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e - \u0a38\u0a2e\u0a3e\u0a1c\u0a3f\u0a15 \u0a16\u0a4b\u0a1c \u0a15\u0a47\u0a02\u0a26\u0a30","description":"\u0a38\u0a3e\u0a21\u0a47 \u0a15\u0a4b\u0a32 \u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06 \u0a26\u0a40 \u0a06\u0a35\u0a3e\u0a1c\u0a3c \u0a28\u0a42\u0a70 \u0a39\u0a3e\u0a38\u0a32 \u0a15\u0a30\u0a28 \u0a32\u0a08 \u0a35\u0a3f\u0a27\u0a40 \u0a05\u0a24\u0a47 \u0a24\u0a15\u0a28\u0a3e\u0a32\u0a4b\u0a1c\u0a40 \u0a26\u0a4b\u0a35\u0a47\u0a02 \u0a39\u0a28\u0964","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/srcentre.com.au\/pa\/\u0a16\u0a4b\u0a1c-\u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e\/","og_locale":"pa_IN","og_type":"article","og_title":"Research innovation","og_description":"We have both the methodology and technology to capture the voice of Australia.","og_url":"https:\/\/srcentre.com.au\/pa\/\u0a16\u0a4b\u0a1c-\u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e\/","og_site_name":"Social Research Centre","article_publisher":"https:\/\/www.facebook.com\/SRCentreAUS\/","article_modified_time":"2024-02-16T02:16:04+00:00","twitter_card":"summary_large_image","twitter_site":"@SRCentreAUS","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/srcentre.com.au\/research-innovation\/","url":"https:\/\/srcentre.com.au\/research-innovation\/","name":"\u0a16\u0a4b\u0a1c \u0a28\u0a35\u0a40\u0a28\u0a24\u0a3e - \u0a38\u0a2e\u0a3e\u0a1c\u0a3f\u0a15 \u0a16\u0a4b\u0a1c \u0a15\u0a47\u0a02\u0a26\u0a30","isPartOf":{"@id":"https:\/\/srcentre.com.au\/#website"},"datePublished":"2023-07-17T06:29:28+00:00","dateModified":"2024-02-16T02:16:04+00:00","description":"\u0a38\u0a3e\u0a21\u0a47 \u0a15\u0a4b\u0a32 \u0a06\u0a38\u0a1f\u0a4d\u0a30\u0a47\u0a32\u0a40\u0a06 \u0a26\u0a40 \u0a06\u0a35\u0a3e\u0a1c\u0a3c \u0a28\u0a42\u0a70 \u0a39\u0a3e\u0a38\u0a32 \u0a15\u0a30\u0a28 \u0a32\u0a08 \u0a35\u0a3f\u0a27\u0a40 \u0a05\u0a24\u0a47 \u0a24\u0a15\u0a28\u0a3e\u0a32\u0a4b\u0a1c\u0a40 \u0a26\u0a4b\u0a35\u0a47\u0a02 \u0a39\u0a28\u0964","breadcrumb":{"@id":"https:\/\/srcentre.com.au\/research-innovation\/#breadcrumb"},"inLanguage":"pa-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/srcentre.com.au\/research-innovation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/srcentre.com.au\/research-innovation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/srcentre.com.au\/"},{"@type":"ListItem","position":2,"name":"Research innovation"}]},{"@type":"WebSite","@id":"https:\/\/srcentre.com.au\/#website","url":"https:\/\/srcentre.com.au\/","name":"\u0a38\u0a2e\u0a3e\u0a1c\u0a3f\u0a15 \u0a16\u0a4b\u0a1c \u0a15\u0a47\u0a02\u0a26\u0a30","description":"\u0a38\u0a2e\u0a3e\u0a1c\u0a3f\u0a15 \u0a16\u0a4b\u0a1c \u0a15\u0a47\u0a02\u0a26\u0a30","publisher":{"@id":"https:\/\/srcentre.com.au\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/srcentre.com.au\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pa-IN"},{"@type":"Organization","@id":"https:\/\/srcentre.com.au\/#organization","name":"\u0a38\u0a2e\u0a3e\u0a1c\u0a3f\u0a15 \u0a16\u0a4b\u0a1c \u0a15\u0a47\u0a02\u0a26\u0a30","url":"https:\/\/srcentre.com.au\/","logo":{"@type":"ImageObject","inLanguage":"pa-IN","@id":"https:\/\/srcentre.com.au\/#\/schema\/logo\/image\/","url":"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/07\/src-icon.svg","contentUrl":"https:\/\/srcentre.com.au\/wp-content\/uploads\/2023\/07\/src-icon.svg","width":135,"height":135,"caption":"Social Research Centre"},"image":{"@id":"https:\/\/srcentre.com.au\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SRCentreAUS\/","https:\/\/x.com\/SRCentreAUS"]}]}},"_links":{"self":[{"href":"https:\/\/srcentre.com.au\/pa\/wp-json\/wp\/v2\/pages\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/srcentre.com.au\/pa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/srcentre.com.au\/pa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/srcentre.com.au\/pa\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/srcentre.com.au\/pa\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":21,"href":"https:\/\/srcentre.com.au\/pa\/wp-json\/wp\/v2\/pages\/121\/revisions"}],"predecessor-version":[{"id":13065,"href":"https:\/\/srcentre.com.au\/pa\/wp-json\/wp\/v2\/pages\/121\/revisions\/13065"}],"wp:attachment":[{"href":"https:\/\/srcentre.com.au\/pa\/wp-json\/wp\/v2\/media?parent=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}